{"id":482595,"date":"2022-01-22T17:26:42","date_gmt":"2022-01-22T15:26:42","guid":{"rendered":"https:\/\/uatv.ua\/?p=482595"},"modified":"2022-01-22T17:26:44","modified_gmt":"2022-01-22T15:26:44","slug":"usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine","status":"publish","type":"post","link":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/","title":{"rendered":"USA intends to deliver five Mi-17 helicopters to Ukraine"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">The U.S. administration has informed Congress of its intention to provide Ukraine with five Mi-17 helicopters, White House Spokesperson Jen Psaki has said.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This was reported by <a href=\"https:\/\/uatv.ua\/en\" target=\"_blank\" rel=\"noreferrer noopener\">UA<\/a> with reference to <a href=\"https:\/\/en.interfax.com.ua\/news\/general\/793291.html\" target=\"_blank\" rel=\"noreferrer noopener\">Interfax-Ukraine<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;On January 19, the Department notified Congress of its intent to deliver five Mi-17 helicopters currently held in DoD inventories to Ukraine under the Excess Defense Articles program,&#8221; the U.S. Embassy in Ukraine <a href=\"https:\/\/twitter.com\/USEmbassyKyiv\/status\/1484852271930355718\" target=\"_blank\" rel=\"noreferrer noopener\">said<\/a>, citing Psaki.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"uk\" dir=\"ltr\">19 \u0441\u0456\u0447\u043d\u044f \u0430\u0434\u043c\u0456\u043d\u0456\u0441\u0442\u0440\u0430\u0446\u0456\u044f \u0421\u0428\u0410 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u043b\u0430 \u041a\u043e\u043d\u0433\u0440\u0435\u0441 \u043f\u0440\u043e \u043d\u0430\u043c\u0456\u0440 \u043d\u0430\u0434\u0430\u0442\u0438 \u0423\u043a\u0440\u0430\u0457\u043d\u0456 \u043f&#39;\u044f\u0442\u044c \u0433\u0435\u043b\u0456\u043a\u043e\u043f\u0442\u0435\u0440\u0456\u0432 \u041c\u0456-17, \u044f\u043a\u0456 \u043d\u0430\u0440\u0430\u0437\u0456 \u0437\u043d\u0430\u0445\u043e\u0434\u044f\u0442\u044c\u0441\u044f \u0432 \u0437\u0430\u043f\u0430\u0441\u0430\u0445 \u041c\u0456\u043d\u0456\u0441\u0442\u0435\u0440\u0441\u0442\u0432\u0430 \u043e\u0431\u043e\u0440\u043e\u043d\u0438 \u0421\u0428\u0410 \u0456 \u043c\u043e\u0436\u0443\u0442\u044c \u0431\u0443\u0442\u0438 \u0434\u043e\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0456 \u0432 \u0440\u0430\u043c\u043a\u0430\u0445 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u0438 \u043d\u0430\u0434\u043b\u0438\u0448\u043a\u043e\u0432\u0438\u0445 \u043e\u0431\u043e\u0440\u043e\u043d\u043d\u0438\u0445 \u0437\u0430\u0441\u043e\u0431\u0456\u0432. <a href=\"https:\/\/t.co\/KqMxVrtkUZ\">pic.twitter.com\/KqMxVrtkUZ<\/a><\/p>&mdash; U.S. Embassy Kyiv (@USEmbassyKyiv) <a href=\"https:\/\/twitter.com\/USEmbassyKyiv\/status\/1484852271930355718?ref_src=twsrc%5Etfw\">January 22, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Read also:<\/strong>&nbsp;<a href=\"https:\/\/uatv.ua\/en\/uk-sends-30-troops-and-2-000-anti-tank-weapons-to-ukraine\/\" target=\"_blank\" rel=\"noreferrer noopener\">UK sends 30 troops and 2,000 anti-tank weapons to Ukraine<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The U.S. administration has informed Congress of its intention to provide Ukraine &#8230;<\/p>\n","protected":false},"author":3,"featured_media":482596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56,49,54,55,50],"tags":[78],"sources":[],"class_list":["post-482595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politics","category-news-en","category-usa-en","category-ukraine-en","category-svit-en","tag-homepage-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>USA intends to deliver five Mi-17 helicopters to Ukraine - Freedom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USA intends to deliver five Mi-17 helicopters to Ukraine - Freedom\" \/>\n<meta property=\"og:description\" content=\"The U.S. administration has informed Congress of its intention to provide Ukraine ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"Freedom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-22T15:26:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-22T15:26:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uatv.ua\/wp-content\/uploads\/2022\/01\/630_360_1470049691-2555-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/\"},\"author\":{\"name\":\"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/#\\\/schema\\\/person\\\/7bce47e71983286745557a9c3b9eaa8b\"},\"headline\":\"USA intends to deliver five Mi-17 helicopters to Ukraine\",\"datePublished\":\"2022-01-22T15:26:42+00:00\",\"dateModified\":\"2022-01-22T15:26:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/\"},\"wordCount\":131,\"image\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uatv.ua\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/630_360_1470049691-2555-2.jpg\",\"keywords\":[\"\u041d\u0430 \u0433\u043b\u0430\u0432\u043d\u0443\u044e (\u0441\u043b\u0430\u0439\u0434\u0435\u0440)\"],\"articleSection\":[\"Politics\",\"News\",\"USA\",\"Ukraine\",\"World\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/\",\"url\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/\",\"name\":\"USA intends to deliver five Mi-17 helicopters to Ukraine - Freedom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uatv.ua\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/630_360_1470049691-2555-2.jpg\",\"datePublished\":\"2022-01-22T15:26:42+00:00\",\"dateModified\":\"2022-01-22T15:26:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/#\\\/schema\\\/person\\\/7bce47e71983286745557a9c3b9eaa8b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uatv.ua\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/630_360_1470049691-2555-2.jpg\",\"contentUrl\":\"https:\\\/\\\/uatv.ua\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/630_360_1470049691-2555-2.jpg\",\"width\":630,\"height\":360,\"caption\":\"Photo Ukrinform\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uatv.ua\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"USA intends to deliver five Mi-17 helicopters to Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/uatv.ua\\\/en\\\/\",\"name\":\"Freedom\",\"description\":\"UATV - UA|TV - International Broadcasting Multimedia Platform of Ukraine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uatv.ua\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uatv.ua\\\/en\\\/#\\\/schema\\\/person\\\/7bce47e71983286745557a9c3b9eaa8b\",\"name\":\"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce3f78e915c0b0f2b7748fae8bdc358859597e964a97384fa6c75016638c0df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce3f78e915c0b0f2b7748fae8bdc358859597e964a97384fa6c75016638c0df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ce3f78e915c0b0f2b7748fae8bdc358859597e964a97384fa6c75016638c0df?s=96&d=mm&r=g\",\"caption\":\"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c\"},\"url\":\"https:\\\/\\\/uatv.ua\\\/en\\\/author\\\/v-lubchak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"USA intends to deliver five Mi-17 helicopters to Ukraine - Freedom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/","og_locale":"en_US","og_type":"article","og_title":"USA intends to deliver five Mi-17 helicopters to Ukraine - Freedom","og_description":"The U.S. administration has informed Congress of its intention to provide Ukraine ...","og_url":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/","og_site_name":"Freedom","article_published_time":"2022-01-22T15:26:42+00:00","article_modified_time":"2022-01-22T15:26:44+00:00","og_image":[{"width":630,"height":360,"url":"https:\/\/uatv.ua\/wp-content\/uploads\/2022\/01\/630_360_1470049691-2555-2.jpg","type":"image\/jpeg"}],"author":"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#article","isPartOf":{"@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/"},"author":{"name":"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c","@id":"https:\/\/uatv.ua\/en\/#\/schema\/person\/7bce47e71983286745557a9c3b9eaa8b"},"headline":"USA intends to deliver five Mi-17 helicopters to Ukraine","datePublished":"2022-01-22T15:26:42+00:00","dateModified":"2022-01-22T15:26:44+00:00","mainEntityOfPage":{"@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/"},"wordCount":131,"image":{"@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/uatv.ua\/wp-content\/uploads\/2022\/01\/630_360_1470049691-2555-2.jpg","keywords":["\u041d\u0430 \u0433\u043b\u0430\u0432\u043d\u0443\u044e (\u0441\u043b\u0430\u0439\u0434\u0435\u0440)"],"articleSection":["Politics","News","USA","Ukraine","World"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/","url":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/","name":"USA intends to deliver five Mi-17 helicopters to Ukraine - Freedom","isPartOf":{"@id":"https:\/\/uatv.ua\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/uatv.ua\/wp-content\/uploads\/2022\/01\/630_360_1470049691-2555-2.jpg","datePublished":"2022-01-22T15:26:42+00:00","dateModified":"2022-01-22T15:26:44+00:00","author":{"@id":"https:\/\/uatv.ua\/en\/#\/schema\/person\/7bce47e71983286745557a9c3b9eaa8b"},"breadcrumb":{"@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#primaryimage","url":"https:\/\/uatv.ua\/wp-content\/uploads\/2022\/01\/630_360_1470049691-2555-2.jpg","contentUrl":"https:\/\/uatv.ua\/wp-content\/uploads\/2022\/01\/630_360_1470049691-2555-2.jpg","width":630,"height":360,"caption":"Photo Ukrinform"},{"@type":"BreadcrumbList","@id":"https:\/\/uatv.ua\/en\/usa-intends-to-deliver-five-mi-17-helicopters-to-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uatv.ua\/en\/"},{"@type":"ListItem","position":2,"name":"USA intends to deliver five Mi-17 helicopters to Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/uatv.ua\/en\/#website","url":"https:\/\/uatv.ua\/en\/","name":"Freedom","description":"UATV - UA|TV - International Broadcasting Multimedia Platform of Ukraine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uatv.ua\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/uatv.ua\/en\/#\/schema\/person\/7bce47e71983286745557a9c3b9eaa8b","name":"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3ce3f78e915c0b0f2b7748fae8bdc358859597e964a97384fa6c75016638c0df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ce3f78e915c0b0f2b7748fae8bdc358859597e964a97384fa6c75016638c0df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ce3f78e915c0b0f2b7748fae8bdc358859597e964a97384fa6c75016638c0df?s=96&d=mm&r=g","caption":"\u041b\u0443\u0431\u0447\u0430\u043a \u0412\u0430\u0434\u0438\u043c"},"url":"https:\/\/uatv.ua\/en\/author\/v-lubchak\/"}]}},"_links":{"self":[{"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/posts\/482595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/comments?post=482595"}],"version-history":[{"count":0,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/posts\/482595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/media\/482596"}],"wp:attachment":[{"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/media?parent=482595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/categories?post=482595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/tags?post=482595"},{"taxonomy":"sources","embeddable":true,"href":"https:\/\/uatv.ua\/en\/wp-json\/wp\/v2\/sources?post=482595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}